{"id":229787,"date":"2025-06-05T08:49:12","date_gmt":"2025-06-05T07:49:12","guid":{"rendered":"https:\/\/cbscompany.com\/machines\/senza-categoria\/uteco-onyx-876-gl-150-year-2006\/"},"modified":"2026-04-16T11:33:50","modified_gmt":"2026-04-16T10:33:50","slug":"uteco-onyx-876-gl-150-year-2006","status":"publish","type":"product","link":"https:\/\/cbscompany.com\/it\/machines\/stampanti-flexo\/stampanti-flessografiche-a-tamburo-centrale-c-i-per-carta\/uteco-onyx-876-gl-150-year-2006\/","title":{"rendered":"Uteco Onyx 876 GL 150 anno 2006"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row content_placement=&#8221;top&#8221;][vc_column css=&#8221;.vc_custom_1532433256788{margin-right: 15px !important;}&#8221; offset=&#8221;vc_col-md-8&#8243;]\n\t\t<div id=\"wd-6762a1cd5d77e\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6762a1cd5d77e wd-title-color-default wd-title-style-default text-left vc_custom_1734517115142 wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title  wd-font-weight-600 wd-fontsize-m\" >Uteco Onyx 876 GL 150 anno 2006<\/h4>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_row_inner css=&#8221;.vc_custom_1628672714565{margin-bottom: 35px !important;border-bottom-width: 0px !important;padding-bottom: 25px !important;border-bottom-color: rgba(129,129,129,0.2) !important;border-bottom-style: solid !important;}&#8221; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1532346102929{padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]<\/p>\n<ul>\n<li aria-level=\"1\"><b>Marchio: Uteco<\/b><\/li>\n<li aria-level=\"1\"><b>Tipo: Onyx 876 GL 150<\/b><\/li>\n<li aria-level=\"1\"><b>Anno: 2006<\/b><\/li>\n<li aria-level=\"1\"><b>Completamente controllato e riparato dall&#8217;ingegnere Uteco nel mese di aprile del 2026.<\/b><\/li>\n<li aria-level=\"1\"><b>Tamburo centrale<\/b><\/li>\n<li aria-level=\"1\"><b>Senza ingranaggi<\/b><\/li>\n<li aria-level=\"1\"><b>8 + 1 colori<\/b><\/li>\n<li aria-level=\"1\"><span style=\"font-weight: 400;\">Larghezza massima del materiale: 1550 mm<\/span><\/li>\n<li aria-level=\"1\"><span style=\"font-weight: 400;\">Larghezza massima di stampa: 1500 mm<\/span><\/li>\n<li aria-level=\"1\"><span style=\"font-weight: 400;\">Ripetizioni di stampa min-max: 400-760 mm<\/span><\/li>\n<li aria-level=\"1\"><span style=\"font-weight: 400;\">Velocit\u00e0 meccanica: 365 m\/min<\/span><\/li>\n<li aria-level=\"1\"><span style=\"font-weight: 400;\">Guida web dell&#8217;OPG per l&#8217;inserimento dei materiali<\/span><\/li>\n<li aria-level=\"1\"><span style=\"font-weight: 400;\">Asciugatura: batterie elettriche<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Ricircolo: manuale  <\/span><\/li>\n<li><span style=\"font-weight: 400;\">Svolgitore Monoasse<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1532346106600{padding-top: 0px !important;}&#8221;][vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]<\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Diametro dello svolgitore: 1270 mm<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Guida web: OPG<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Telecamera: BST SHS 3000<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sollevatore idraulico della bobina<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Avvolgitore Monoasse<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Diametro dell&#8217;avvolgitore: 1270 mm<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\">Manicotti: 2 serie incluse<\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Anilox: 2 x 220 vol. 18; 2 x 80 vol. 18 Simec; 2 x 160 vol.   18<\/span><\/li>\n<li aria-level=\"1\"><span style=\"font-weight: 400;\">Sollevatore idraulico della bobina<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Taglierina a lama circolare<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Guida web della piattaforma OPG<\/span><\/li>\n<li aria-level=\"1\"><span style=\"font-weight: 400;\">Dimensioni complessive: 18315 x 5147 x 7600 m<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Visibile in funzione<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Immediatamente disponibile<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column offset=&#8221;vc_col-md-4&#8243;]\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t\t\t\t\t\t<div id=\"wd-6762a616cfed7\" class=\" wd-rs-6762a616cfed7 wd-info-box wd-wpb text-left box-icon-align-left box-style-shadow color-scheme- wd-bg-none wd-off-anim wpb_animate_when_almost_visible wpb_bounceIn bounceIn wd-anim-name_bounceIn wd-items-top \">\n\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\t<div class=\"info-box-subtitle subtitle-color-default wd-fontsize-xs subtitle-style-default\">Informazioni su Uteco Onyx 876 GL 150 anno 2006<\/div><h4 class=\"info-box-title title box-title-style-default wd-fontsize-m\">Informazioni sulla posizione<\/h4>\t\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"><p>Disponibile nella regione: <strong style=\"color: blue;\"><a href=\"https:\/\/cbscompany.com\/it\/il-mio-account\/?redirect_to=%2Fit%2Fwp-json%2Fwp%2Fv2%2Fproduct%2F229787\" class=\"simplemodal-login\">Accedi per vedere la posizione<\/a><\/strong><\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t\t<style>#wd-6762a616cfed7 .info-box-icon {background-color:  !important;}<\/style>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Uteco Onyx 876 GL 150, anno 2006, \u00e8 una stampante flessografica a 8+1 colori con tamburo centrale progettata per lavorare con i papaer. La larghezza massima di stampa \u00e8 di 1500 mm.  <span style=\"font-weight: 400;\">Immediatamente disponibile<\/span><\/p>\n","protected":false},"featured_media":243997,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"om_disable_all_campaigns":false},"year-of-production":[],"product_brand":[],"product_cat":[1698,1699],"product_tag":[2296,2155,2195,2297,3546,2088],"class_list":["post-229787","product","type-product","status-publish","has-post-thumbnail","product_cat-stampanti-flexo","product_cat-stampanti-flessografiche-a-tamburo-centrale-c-i-per-carta","product_tag-81-color-it","product_tag-year-2006-it","product_tag-c-i-it","product_tag-onyx-876-gl-150-it","product_tag-central-drum-it-2","product_tag-uteco-it","first","instock","sold-individually","shipping-taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/product\/229787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/comments?post=229787"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/media\/243997"}],"wp:attachment":[{"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/media?parent=229787"}],"wp:term":[{"taxonomy":"year-of-production","embeddable":true,"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/year-of-production?post=229787"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/product_brand?post=229787"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/product_cat?post=229787"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cbscompany.com\/it\/wp-json\/wp\/v2\/product_tag?post=229787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}